{"id":3189,"date":"2025-07-13T21:11:11","date_gmt":"2025-07-14T02:11:11","guid":{"rendered":"https:\/\/www.basler.com\/product\/es-series-protection-relays\/"},"modified":"2026-03-02T09:50:28","modified_gmt":"2026-03-02T15:50:28","slug":"es-series-protection-relays","status":"publish","type":"product","link":"https:\/\/www.basler.com\/de\/product\/es-series-protection-relays\/","title":{"rendered":"ES Series Protection Relays"},"content":{"rendered":"<section  data-block-id=\"hammer_block_a1d8f29c268dcecbf7fd230c95b757d6\" data-block=\"hero-10\" class=\"block block-hero-10 hero-10\" id=\"overview\">    <div class=\"wrapper\">\n        <div class=\"left_content\">\n                            <div class=\"headline-wrapper\">\n                                            <strong class=\"overline\">Protective Relay Systems<\/strong>\n                    \n                    <h1 id=\"hammer_component_6a04f70d4b7ad\" data-component=\"headline\" class=\"component component-headline headline style-default\">ES Series Protection Relays<\/h1>\n                <\/div>\n            \n            \n                                                <div class=\"buttons\">\n                                                                                                    \n                                                                                                                                                                    <a id=\"hammer_component_6a04f70d4c0e6\" data-component=\"button\" class=\"component component-button button style-secondary\" href=\"?languages=deutsch&amp;products=3189,37019,37018,37017,37016,37015,37014,37013,37012,37011,37010,37009,37008,37007,37006,37005,37004,37003,37002\" target=\"\" title=\"View Resources\" aria-label=\"View Resources\">    <span class=\"button-wrapper\">\n                    <strong class=\"button-text\">View Resources<\/strong>\n        \n                    <span class=\"icon-wrapper\" aria-hidden=\"true\">\n                <span class=\"button-icon\">\n                    <?xml version=\"1.0\" encoding=\"UTF-8\"?> <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"8\" height=\"8\" viewbox=\"0 0 8 8\" fill=\"currentColor\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M7.25606 1.27007L0.526065 8L0 7.47393L6.73 0.743975H0.789112V0H8.00004V7.21087H7.25606V1.27007Z\" fill=\"currentColor\"><\/path><\/svg>                 <\/span>\n            <\/span>\n            <\/span>\n    <\/a>\n                                            <\/div>\n                                    <\/div>\n\n                    <div class=\"right_content\">\n                <div class=\"slider slider-main\">\n                    <div class=\"swiper-wrapper\">\n                                                    <div class=\"swiper-slide\">\n                                                                    <figure id=\"hammer_component_6a04f70d4c326\" data-component=\"image\" class=\"component component-image image\">\n        <picture class=\"picture\">\n            <img decoding=\"async\" width=\"1084\" height=\"600\" src=\"https:\/\/www.basler.com\/wp-content\/uploads\/2025\/07\/ES-27_ES-59_ES-2759-Edit-Small_web.jpg\" class=\"img\" alt=\"\" loading=\"lazy\" title=\"\" srcset=\"https:\/\/www.basler.com\/wp-content\/uploads\/2025\/07\/ES-27_ES-59_ES-2759-Edit-Small_web.jpg 1084w, https:\/\/www.basler.com\/wp-content\/uploads\/2025\/07\/ES-27_ES-59_ES-2759-Edit-Small_web-768x425.jpg 768w, https:\/\/www.basler.com\/wp-content\/uploads\/2025\/07\/ES-27_ES-59_ES-2759-Edit-Small_web-1024x567.jpg 1024w, https:\/\/www.basler.com\/wp-content\/uploads\/2025\/07\/ES-27_ES-59_ES-2759-Edit-Small_web-150x83.jpg 150w, https:\/\/www.basler.com\/wp-content\/uploads\/2025\/07\/ES-27_ES-59_ES-2759-Edit-Small_web-414x229.jpg 414w\" sizes=\"auto, (max-width: 1084px) 100vw, 1084px\">        <\/picture>\n\n            <\/figure>\n                                                            <\/div>\n                                                    <div class=\"swiper-slide\">\n                                                                    <figure id=\"hammer_component_6a04f70d4c7ed\" data-component=\"image\" class=\"component component-image image\">\n        <picture class=\"picture\">\n            <img decoding=\"async\" width=\"1084\" height=\"600\" src=\"https:\/\/www.basler.com\/wp-content\/uploads\/2025\/07\/Product-Page-ES-27-and-ES-25-5.jpg\" class=\"img\" alt=\"\" loading=\"lazy\" title=\"\" srcset=\"https:\/\/www.basler.com\/wp-content\/uploads\/2025\/07\/Product-Page-ES-27-and-ES-25-5.jpg 1084w, https:\/\/www.basler.com\/wp-content\/uploads\/2025\/07\/Product-Page-ES-27-and-ES-25-5-768x425.jpg 768w, https:\/\/www.basler.com\/wp-content\/uploads\/2025\/07\/Product-Page-ES-27-and-ES-25-5-1024x567.jpg 1024w, https:\/\/www.basler.com\/wp-content\/uploads\/2025\/07\/Product-Page-ES-27-and-ES-25-5-150x83.jpg 150w, https:\/\/www.basler.com\/wp-content\/uploads\/2025\/07\/Product-Page-ES-27-and-ES-25-5-414x229.jpg 414w\" sizes=\"auto, (max-width: 1084px) 100vw, 1084px\">        <\/picture>\n\n            <\/figure>\n                                                            <\/div>\n                                                    <div class=\"swiper-slide\">\n                                                                    <figure id=\"hammer_component_6a04f70d4ccce\" data-component=\"image\" class=\"component component-image image\">\n        <picture class=\"picture\">\n            <img decoding=\"async\" width=\"1084\" height=\"600\" src=\"https:\/\/www.basler.com\/wp-content\/uploads\/2025\/02\/1620.png\" class=\"img\" alt=\"ES-27 Unterspannungsrelais auf Tragschiene\" loading=\"lazy\" title=\"\" srcset=\"https:\/\/www.basler.com\/wp-content\/uploads\/2025\/02\/1620.png 1084w, https:\/\/www.basler.com\/wp-content\/uploads\/2025\/02\/1620-768x425.png 768w, https:\/\/www.basler.com\/wp-content\/uploads\/2025\/02\/1620-1024x567.png 1024w, https:\/\/www.basler.com\/wp-content\/uploads\/2025\/02\/1620-150x83.png 150w, https:\/\/www.basler.com\/wp-content\/uploads\/2025\/02\/1620-414x229.png 414w\" sizes=\"auto, (max-width: 1084px) 100vw, 1084px\">        <\/picture>\n\n            <\/figure>\n                                                            <\/div>\n                                                    <div class=\"swiper-slide\">\n                                                                    <figure id=\"hammer_component_6a04f70d4d0d9\" data-component=\"image\" class=\"component component-image image\">\n        <picture class=\"picture\">\n            <img decoding=\"async\" width=\"1084\" height=\"600\" src=\"https:\/\/www.basler.com\/wp-content\/uploads\/2025\/02\/1556.jpg\" class=\"img\" alt=\"ES-49 Temperaturrelais\" loading=\"lazy\" title=\"\" srcset=\"https:\/\/www.basler.com\/wp-content\/uploads\/2025\/02\/1556.jpg 1084w, https:\/\/www.basler.com\/wp-content\/uploads\/2025\/02\/1556-768x425.jpg 768w, https:\/\/www.basler.com\/wp-content\/uploads\/2025\/02\/1556-1024x567.jpg 1024w, https:\/\/www.basler.com\/wp-content\/uploads\/2025\/02\/1556-150x83.jpg 150w, https:\/\/www.basler.com\/wp-content\/uploads\/2025\/02\/1556-414x229.jpg 414w\" sizes=\"auto, (max-width: 1084px) 100vw, 1084px\">        <\/picture>\n\n            <\/figure>\n                                                            <\/div>\n                                                    <div class=\"swiper-slide\">\n                                                                    <figure id=\"hammer_component_6a04f70d4d446\" data-component=\"image\" class=\"component component-image image\">\n        <picture class=\"picture\">\n            <img decoding=\"async\" width=\"1084\" height=\"600\" src=\"https:\/\/www.basler.com\/wp-content\/uploads\/2025\/02\/1555.jpg\" class=\"img\" alt=\"ES-47 Phasensequenzrelais\" loading=\"lazy\" title=\"\" srcset=\"https:\/\/www.basler.com\/wp-content\/uploads\/2025\/02\/1555.jpg 1084w, https:\/\/www.basler.com\/wp-content\/uploads\/2025\/02\/1555-768x425.jpg 768w, https:\/\/www.basler.com\/wp-content\/uploads\/2025\/02\/1555-1024x567.jpg 1024w, https:\/\/www.basler.com\/wp-content\/uploads\/2025\/02\/1555-150x83.jpg 150w, https:\/\/www.basler.com\/wp-content\/uploads\/2025\/02\/1555-414x229.jpg 414w\" sizes=\"auto, (max-width: 1084px) 100vw, 1084px\">        <\/picture>\n\n            <\/figure>\n                                                            <\/div>\n                                                    <div class=\"swiper-slide\">\n                                                                    <figure id=\"hammer_component_6a04f70d4d735\" data-component=\"image\" class=\"component component-image image\">\n        <picture class=\"picture\">\n            <img decoding=\"async\" width=\"1084\" height=\"600\" src=\"https:\/\/www.basler.com\/wp-content\/uploads\/2025\/02\/1629.png\" class=\"img\" alt=\"Leistungsrelais ES-55\" loading=\"lazy\" title=\"\" srcset=\"https:\/\/www.basler.com\/wp-content\/uploads\/2025\/02\/1629.png 1084w, https:\/\/www.basler.com\/wp-content\/uploads\/2025\/02\/1629-768x425.png 768w, https:\/\/www.basler.com\/wp-content\/uploads\/2025\/02\/1629-1024x567.png 1024w, https:\/\/www.basler.com\/wp-content\/uploads\/2025\/02\/1629-150x83.png 150w, https:\/\/www.basler.com\/wp-content\/uploads\/2025\/02\/1629-414x229.png 414w\" sizes=\"auto, (max-width: 1084px) 100vw, 1084px\">        <\/picture>\n\n            <\/figure>\n                                                            <\/div>\n                                                    <div class=\"swiper-slide\">\n                                                                    <figure id=\"hammer_component_6a04f70d4da41\" data-component=\"image\" class=\"component component-image image\">\n        <picture class=\"picture\">\n            <img decoding=\"async\" width=\"1084\" height=\"600\" src=\"https:\/\/www.basler.com\/wp-content\/uploads\/2025\/02\/1546.jpg\" class=\"img\" alt=\"Standard DIN-Schiene 999,99 mm\" loading=\"lazy\" title=\"\" srcset=\"https:\/\/www.basler.com\/wp-content\/uploads\/2025\/02\/1546.jpg 1084w, https:\/\/www.basler.com\/wp-content\/uploads\/2025\/02\/1546-768x425.jpg 768w, https:\/\/www.basler.com\/wp-content\/uploads\/2025\/02\/1546-1024x567.jpg 1024w, https:\/\/www.basler.com\/wp-content\/uploads\/2025\/02\/1546-150x83.jpg 150w, https:\/\/www.basler.com\/wp-content\/uploads\/2025\/02\/1546-414x229.jpg 414w\" sizes=\"auto, (max-width: 1084px) 100vw, 1084px\">        <\/picture>\n\n            <\/figure>\n                                                            <\/div>\n                                                    <div class=\"swiper-slide\">\n                                                                    <figure id=\"hammer_component_6a04f70d4ddb2\" data-component=\"image\" class=\"component component-image image\">\n        <picture class=\"picture\">\n            <img decoding=\"async\" width=\"1084\" height=\"600\" src=\"https:\/\/www.basler.com\/wp-content\/uploads\/2025\/02\/1547.jpg\" class=\"img\" alt=\"Tragschiene 76,2 mm\" loading=\"lazy\" title=\"\" srcset=\"https:\/\/www.basler.com\/wp-content\/uploads\/2025\/02\/1547.jpg 1084w, https:\/\/www.basler.com\/wp-content\/uploads\/2025\/02\/1547-768x425.jpg 768w, https:\/\/www.basler.com\/wp-content\/uploads\/2025\/02\/1547-1024x567.jpg 1024w, https:\/\/www.basler.com\/wp-content\/uploads\/2025\/02\/1547-150x83.jpg 150w, https:\/\/www.basler.com\/wp-content\/uploads\/2025\/02\/1547-414x229.jpg 414w\" sizes=\"auto, (max-width: 1084px) 100vw, 1084px\">        <\/picture>\n\n            <\/figure>\n                                                            <\/div>\n                                                    <div class=\"swiper-slide\">\n                                                                    <figure id=\"hammer_component_6a04f70d4e062\" data-component=\"image\" class=\"component component-image image\">\n        <picture class=\"picture\">\n            <img decoding=\"async\" width=\"1084\" height=\"600\" src=\"https:\/\/www.basler.com\/wp-content\/uploads\/2025\/02\/1548.jpg\" class=\"img\" alt=\"Tragschiene 139,7 mm\" loading=\"lazy\" title=\"\" srcset=\"https:\/\/www.basler.com\/wp-content\/uploads\/2025\/02\/1548.jpg 1084w, https:\/\/www.basler.com\/wp-content\/uploads\/2025\/02\/1548-768x425.jpg 768w, https:\/\/www.basler.com\/wp-content\/uploads\/2025\/02\/1548-1024x567.jpg 1024w, https:\/\/www.basler.com\/wp-content\/uploads\/2025\/02\/1548-150x83.jpg 150w, https:\/\/www.basler.com\/wp-content\/uploads\/2025\/02\/1548-414x229.jpg 414w\" sizes=\"auto, (max-width: 1084px) 100vw, 1084px\">        <\/picture>\n\n            <\/figure>\n                                                            <\/div>\n                                                    <div class=\"swiper-slide\">\n                                                                    <figure id=\"hammer_component_6a04f70d4e3db\" data-component=\"image\" class=\"component component-image image\">\n        <picture class=\"picture\">\n            <img decoding=\"async\" width=\"1084\" height=\"600\" src=\"https:\/\/www.basler.com\/wp-content\/uploads\/2025\/02\/1549.jpg\" class=\"img\" alt=\"Tragschiene 203,2 mm\" loading=\"lazy\" title=\"\" srcset=\"https:\/\/www.basler.com\/wp-content\/uploads\/2025\/02\/1549.jpg 1084w, https:\/\/www.basler.com\/wp-content\/uploads\/2025\/02\/1549-768x425.jpg 768w, https:\/\/www.basler.com\/wp-content\/uploads\/2025\/02\/1549-1024x567.jpg 1024w, https:\/\/www.basler.com\/wp-content\/uploads\/2025\/02\/1549-150x83.jpg 150w, https:\/\/www.basler.com\/wp-content\/uploads\/2025\/02\/1549-414x229.jpg 414w\" sizes=\"auto, (max-width: 1084px) 100vw, 1084px\">        <\/picture>\n\n            <\/figure>\n                                                            <\/div>\n                                            <\/div>\n                <\/div>\n\n                                    <div class=\"slider slider-vertical\">\n                        <div class=\"swiper-wrapper\">\n                                                            <div class=\"swiper-slide\">\n                                                                            <figure id=\"hammer_component_6a04f70d4e707\" data-component=\"image\" class=\"component component-image image\">\n        <picture class=\"picture\">\n            <img decoding=\"async\" width=\"1084\" height=\"600\" src=\"https:\/\/www.basler.com\/wp-content\/uploads\/2025\/07\/ES-27_ES-59_ES-2759-Edit-Small_web.jpg\" class=\"img\" alt=\"\" loading=\"lazy\" title=\"\" srcset=\"https:\/\/www.basler.com\/wp-content\/uploads\/2025\/07\/ES-27_ES-59_ES-2759-Edit-Small_web.jpg 1084w, https:\/\/www.basler.com\/wp-content\/uploads\/2025\/07\/ES-27_ES-59_ES-2759-Edit-Small_web-768x425.jpg 768w, https:\/\/www.basler.com\/wp-content\/uploads\/2025\/07\/ES-27_ES-59_ES-2759-Edit-Small_web-1024x567.jpg 1024w, https:\/\/www.basler.com\/wp-content\/uploads\/2025\/07\/ES-27_ES-59_ES-2759-Edit-Small_web-150x83.jpg 150w, https:\/\/www.basler.com\/wp-content\/uploads\/2025\/07\/ES-27_ES-59_ES-2759-Edit-Small_web-414x229.jpg 414w\" sizes=\"auto, (max-width: 1084px) 100vw, 1084px\">        <\/picture>\n\n            <\/figure>\n                                                                    <\/div>\n                                                            <div class=\"swiper-slide\">\n                                                                            <figure id=\"hammer_component_6a04f70d4e9ec\" data-component=\"image\" class=\"component component-image image\">\n        <picture class=\"picture\">\n            <img decoding=\"async\" width=\"1084\" height=\"600\" src=\"https:\/\/www.basler.com\/wp-content\/uploads\/2025\/07\/Product-Page-ES-27-and-ES-25-5.jpg\" class=\"img\" alt=\"\" loading=\"lazy\" title=\"\" srcset=\"https:\/\/www.basler.com\/wp-content\/uploads\/2025\/07\/Product-Page-ES-27-and-ES-25-5.jpg 1084w, https:\/\/www.basler.com\/wp-content\/uploads\/2025\/07\/Product-Page-ES-27-and-ES-25-5-768x425.jpg 768w, https:\/\/www.basler.com\/wp-content\/uploads\/2025\/07\/Product-Page-ES-27-and-ES-25-5-1024x567.jpg 1024w, https:\/\/www.basler.com\/wp-content\/uploads\/2025\/07\/Product-Page-ES-27-and-ES-25-5-150x83.jpg 150w, https:\/\/www.basler.com\/wp-content\/uploads\/2025\/07\/Product-Page-ES-27-and-ES-25-5-414x229.jpg 414w\" sizes=\"auto, (max-width: 1084px) 100vw, 1084px\">        <\/picture>\n\n            <\/figure>\n                                                                    <\/div>\n                                                            <div class=\"swiper-slide\">\n                                                                            <figure id=\"hammer_component_6a04f70d4ed27\" data-component=\"image\" class=\"component component-image image\">\n        <picture class=\"picture\">\n            <img decoding=\"async\" width=\"1084\" height=\"600\" src=\"https:\/\/www.basler.com\/wp-content\/uploads\/2025\/02\/1620.png\" class=\"img\" alt=\"ES-27 Unterspannungsrelais auf Tragschiene\" loading=\"lazy\" title=\"\" srcset=\"https:\/\/www.basler.com\/wp-content\/uploads\/2025\/02\/1620.png 1084w, https:\/\/www.basler.com\/wp-content\/uploads\/2025\/02\/1620-768x425.png 768w, https:\/\/www.basler.com\/wp-content\/uploads\/2025\/02\/1620-1024x567.png 1024w, https:\/\/www.basler.com\/wp-content\/uploads\/2025\/02\/1620-150x83.png 150w, https:\/\/www.basler.com\/wp-content\/uploads\/2025\/02\/1620-414x229.png 414w\" sizes=\"auto, (max-width: 1084px) 100vw, 1084px\">        <\/picture>\n\n            <\/figure>\n                                                                    <\/div>\n                                                            <div class=\"swiper-slide\">\n                                                                            <figure id=\"hammer_component_6a04f70d4f065\" data-component=\"image\" class=\"component component-image image\">\n        <picture class=\"picture\">\n            <img decoding=\"async\" width=\"1084\" height=\"600\" src=\"https:\/\/www.basler.com\/wp-content\/uploads\/2025\/02\/1556.jpg\" class=\"img\" alt=\"ES-49 Temperaturrelais\" loading=\"lazy\" title=\"\" srcset=\"https:\/\/www.basler.com\/wp-content\/uploads\/2025\/02\/1556.jpg 1084w, https:\/\/www.basler.com\/wp-content\/uploads\/2025\/02\/1556-768x425.jpg 768w, https:\/\/www.basler.com\/wp-content\/uploads\/2025\/02\/1556-1024x567.jpg 1024w, https:\/\/www.basler.com\/wp-content\/uploads\/2025\/02\/1556-150x83.jpg 150w, https:\/\/www.basler.com\/wp-content\/uploads\/2025\/02\/1556-414x229.jpg 414w\" sizes=\"auto, (max-width: 1084px) 100vw, 1084px\">        <\/picture>\n\n            <\/figure>\n                                                                    <\/div>\n                                                            <div class=\"swiper-slide\">\n                                                                            <figure id=\"hammer_component_6a04f70d4f3cd\" data-component=\"image\" class=\"component component-image image\">\n        <picture class=\"picture\">\n            <img decoding=\"async\" width=\"1084\" height=\"600\" src=\"https:\/\/www.basler.com\/wp-content\/uploads\/2025\/02\/1555.jpg\" class=\"img\" alt=\"ES-47 Phasensequenzrelais\" loading=\"lazy\" title=\"\" srcset=\"https:\/\/www.basler.com\/wp-content\/uploads\/2025\/02\/1555.jpg 1084w, https:\/\/www.basler.com\/wp-content\/uploads\/2025\/02\/1555-768x425.jpg 768w, https:\/\/www.basler.com\/wp-content\/uploads\/2025\/02\/1555-1024x567.jpg 1024w, https:\/\/www.basler.com\/wp-content\/uploads\/2025\/02\/1555-150x83.jpg 150w, https:\/\/www.basler.com\/wp-content\/uploads\/2025\/02\/1555-414x229.jpg 414w\" sizes=\"auto, (max-width: 1084px) 100vw, 1084px\">        <\/picture>\n\n            <\/figure>\n                                                                    <\/div>\n                                                            <div class=\"swiper-slide\">\n                                                                            <figure id=\"hammer_component_6a04f70d4f74a\" data-component=\"image\" class=\"component component-image image\">\n        <picture class=\"picture\">\n            <img decoding=\"async\" width=\"1084\" height=\"600\" src=\"https:\/\/www.basler.com\/wp-content\/uploads\/2025\/02\/1629.png\" class=\"img\" alt=\"Leistungsrelais ES-55\" loading=\"lazy\" title=\"\" srcset=\"https:\/\/www.basler.com\/wp-content\/uploads\/2025\/02\/1629.png 1084w, https:\/\/www.basler.com\/wp-content\/uploads\/2025\/02\/1629-768x425.png 768w, https:\/\/www.basler.com\/wp-content\/uploads\/2025\/02\/1629-1024x567.png 1024w, https:\/\/www.basler.com\/wp-content\/uploads\/2025\/02\/1629-150x83.png 150w, https:\/\/www.basler.com\/wp-content\/uploads\/2025\/02\/1629-414x229.png 414w\" sizes=\"auto, (max-width: 1084px) 100vw, 1084px\">        <\/picture>\n\n            <\/figure>\n                                                                    <\/div>\n                                                            <div class=\"swiper-slide\">\n                                                                            <figure id=\"hammer_component_6a04f70d4fa05\" data-component=\"image\" class=\"component component-image image\">\n        <picture class=\"picture\">\n            <img decoding=\"async\" width=\"1084\" height=\"600\" src=\"https:\/\/www.basler.com\/wp-content\/uploads\/2025\/02\/1546.jpg\" class=\"img\" alt=\"Standard DIN-Schiene 999,99 mm\" loading=\"lazy\" title=\"\" srcset=\"https:\/\/www.basler.com\/wp-content\/uploads\/2025\/02\/1546.jpg 1084w, https:\/\/www.basler.com\/wp-content\/uploads\/2025\/02\/1546-768x425.jpg 768w, https:\/\/www.basler.com\/wp-content\/uploads\/2025\/02\/1546-1024x567.jpg 1024w, https:\/\/www.basler.com\/wp-content\/uploads\/2025\/02\/1546-150x83.jpg 150w, https:\/\/www.basler.com\/wp-content\/uploads\/2025\/02\/1546-414x229.jpg 414w\" sizes=\"auto, (max-width: 1084px) 100vw, 1084px\">        <\/picture>\n\n            <\/figure>\n                                                                    <\/div>\n                                                            <div class=\"swiper-slide\">\n                                                                            <figure id=\"hammer_component_6a04f70d4fd9e\" data-component=\"image\" class=\"component component-image image\">\n        <picture class=\"picture\">\n            <img decoding=\"async\" width=\"1084\" height=\"600\" src=\"https:\/\/www.basler.com\/wp-content\/uploads\/2025\/02\/1547.jpg\" class=\"img\" alt=\"Tragschiene 76,2 mm\" loading=\"lazy\" title=\"\" srcset=\"https:\/\/www.basler.com\/wp-content\/uploads\/2025\/02\/1547.jpg 1084w, https:\/\/www.basler.com\/wp-content\/uploads\/2025\/02\/1547-768x425.jpg 768w, https:\/\/www.basler.com\/wp-content\/uploads\/2025\/02\/1547-1024x567.jpg 1024w, https:\/\/www.basler.com\/wp-content\/uploads\/2025\/02\/1547-150x83.jpg 150w, https:\/\/www.basler.com\/wp-content\/uploads\/2025\/02\/1547-414x229.jpg 414w\" sizes=\"auto, (max-width: 1084px) 100vw, 1084px\">        <\/picture>\n\n            <\/figure>\n                                                                    <\/div>\n                                                            <div class=\"swiper-slide\">\n                                                                            <figure id=\"hammer_component_6a04f70d50070\" data-component=\"image\" class=\"component component-image image\">\n        <picture class=\"picture\">\n            <img decoding=\"async\" width=\"1084\" height=\"600\" src=\"https:\/\/www.basler.com\/wp-content\/uploads\/2025\/02\/1548.jpg\" class=\"img\" alt=\"Tragschiene 139,7 mm\" loading=\"lazy\" title=\"\" srcset=\"https:\/\/www.basler.com\/wp-content\/uploads\/2025\/02\/1548.jpg 1084w, https:\/\/www.basler.com\/wp-content\/uploads\/2025\/02\/1548-768x425.jpg 768w, https:\/\/www.basler.com\/wp-content\/uploads\/2025\/02\/1548-1024x567.jpg 1024w, https:\/\/www.basler.com\/wp-content\/uploads\/2025\/02\/1548-150x83.jpg 150w, https:\/\/www.basler.com\/wp-content\/uploads\/2025\/02\/1548-414x229.jpg 414w\" sizes=\"auto, (max-width: 1084px) 100vw, 1084px\">        <\/picture>\n\n            <\/figure>\n                                                                    <\/div>\n                                                            <div class=\"swiper-slide\">\n                                                                            <figure id=\"hammer_component_6a04f70d50320\" data-component=\"image\" class=\"component component-image image\">\n        <picture class=\"picture\">\n            <img decoding=\"async\" width=\"1084\" height=\"600\" src=\"https:\/\/www.basler.com\/wp-content\/uploads\/2025\/02\/1549.jpg\" class=\"img\" alt=\"Tragschiene 203,2 mm\" loading=\"lazy\" title=\"\" srcset=\"https:\/\/www.basler.com\/wp-content\/uploads\/2025\/02\/1549.jpg 1084w, https:\/\/www.basler.com\/wp-content\/uploads\/2025\/02\/1549-768x425.jpg 768w, https:\/\/www.basler.com\/wp-content\/uploads\/2025\/02\/1549-1024x567.jpg 1024w, https:\/\/www.basler.com\/wp-content\/uploads\/2025\/02\/1549-150x83.jpg 150w, https:\/\/www.basler.com\/wp-content\/uploads\/2025\/02\/1549-414x229.jpg 414w\" sizes=\"auto, (max-width: 1084px) 100vw, 1084px\">        <\/picture>\n\n            <\/figure>\n                                                                    <\/div>\n                                                    <\/div>\n                    <\/div>\n                            <\/div>\n            <\/div>\n    <\/section>\n\n\n\n<section  data-block-id=\"hammer_block_674ad905cb99cb437c173ffce0397d73\" data-block=\"product-listing-slider\" class=\"block block-product-listing-slider product-listing-slider spacing-top-default spacing-bottom-default\">    <div class=\"wrapper ember-entrance-group\">\n        <header class=\"header ember-entrance\">\n            <h2 id=\"hammer_component_6a04f70d61bec\" data-component=\"headline\" class=\"component component-headline headline style-default\">Products<\/h2>\n\n            <p class=\"text\"><\/p>\n\n            <hr class=\"line\">\n\n            <div class=\"swiper-indicator-wrapper\">\n                <div class=\"swiper-indicator js-indicator\"><\/div>\n                <div class=\"slider-controls js-slider-controls ember-entrance\">\n                    <div id=\"hammer_component_6a04f70d61c88\" data-component=\"swiper-controls\" class=\"component component-swiper-controls swiper-controls js-controls\"><button id=\"hammer_component_6a04f70d61ca0\" data-component=\"icon\" class=\"component component-icon icon button prev js-prev has-style style-dark\">    <span class=\"icon-wrapper\">\n        <?xml version=\"1.0\" encoding=\"UTF-8\"?> <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10\" height=\"10\" viewbox=\"0 0 10 10\" fill=\"currentColor\"><path d=\"M5.71 10L9.88 5.33C9.88 5.33 9.95 5.24 9.97 5.18C9.99 5.12 10 5.06 10 5C10 4.94 9.99 4.88 9.97 4.82C9.95 4.76 9.92 4.71 9.88 4.67L5.71 0L5.13 0.65L8.59 4.53H0V5.46H8.58L5.12 9.34L5.7 9.99L5.71 10Z\" fill=\"currentColor\"><\/path><\/svg>     <\/span>\n    \n            <span class=\"sr-only\">Return to previous slide<\/span>\n    \n    <\/button>\n<button id=\"hammer_component_6a04f70d61d95\" data-component=\"icon\" class=\"component component-icon icon button next js-next has-style style-dark\">    <span class=\"icon-wrapper\">\n        <?xml version=\"1.0\" encoding=\"UTF-8\"?> <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10\" height=\"10\" viewbox=\"0 0 10 10\" fill=\"currentColor\"><path d=\"M5.71 10L9.88 5.33C9.88 5.33 9.95 5.24 9.97 5.18C9.99 5.12 10 5.06 10 5C10 4.94 9.99 4.88 9.97 4.82C9.95 4.76 9.92 4.71 9.88 4.67L5.71 0L5.13 0.65L8.59 4.53H0V5.46H8.58L5.12 9.34L5.7 9.99L5.71 10Z\" fill=\"currentColor\"><\/path><\/svg>     <\/span>\n    \n            <span class=\"sr-only\">Jump to next slide<\/span>\n    \n    <\/button>\n<\/div>\n                <\/div>\n            <\/div>\n        <\/header>\n\n        <div class=\"swiper js-slider-products ember-entrance\">\n            <div class=\"swiper-wrapper\">\n                                    <div class=\"swiper-slide slide\">\n                        <article id=\"hammer_component_6a04f70d61e95\" data-component=\"card-product\" class=\"component component-card-product card-product primary\">\n\t\t<div class=\"image-wrapper\">\n            <figure id=\"hammer_component_6a04f70d751f4\" data-component=\"image\" class=\"component component-image image\">\n        <picture class=\"picture\">\n            <img decoding=\"async\" width=\"414\" height=\"233\" src=\"https:\/\/www.basler.com\/wp-content\/uploads\/2025\/09\/Basler-Default-Image-414x233.jpg\" class=\"img\" alt=\"\" loading=\"lazy\" title=\"\" srcset=\"https:\/\/www.basler.com\/wp-content\/uploads\/2025\/09\/Basler-Default-Image-414x233.jpg 414w, https:\/\/www.basler.com\/wp-content\/uploads\/2025\/09\/Basler-Default-Image-768x432.jpg 768w, https:\/\/www.basler.com\/wp-content\/uploads\/2025\/09\/Basler-Default-Image-1024x576.jpg 1024w, https:\/\/www.basler.com\/wp-content\/uploads\/2025\/09\/Basler-Default-Image-150x84.jpg 150w, https:\/\/www.basler.com\/wp-content\/uploads\/2025\/09\/Basler-Default-Image-1600x900.jpg 1600w, https:\/\/www.basler.com\/wp-content\/uploads\/2025\/09\/Basler-Default-Image.jpg 1920w\" sizes=\"auto, (max-width: 414px) 100vw, 414px\">        <\/picture>\n\n            <\/figure>\n\t\t<\/div>\n\n\t\t<div class=\"infos\">\n            \n            <h3 class=\"title\">KR7F<\/h3>\t\t<\/div>\n\n        <a id=\"hammer_component_6a04f70d757dd\" data-component=\"link\" class=\"component component-link link cover-link style-primary\" href=\"https:\/\/www.basler.com\/de\/product\/kr7f\/\" title=\"KR7F\" target=\"\">        <span class=\"link-text\">KR7F<\/span>\n        <\/a>\n\n                \t<\/article>\n                    <\/div>\n                                    <div class=\"swiper-slide slide\">\n                        <article id=\"hammer_component_6a04f70d75e11\" data-component=\"card-product\" class=\"component component-card-product card-product primary\">\n\t\t<div class=\"image-wrapper\">\n            <figure id=\"hammer_component_6a04f70d787cd\" data-component=\"image\" class=\"component component-image image\">\n        <picture class=\"picture\">\n            <img decoding=\"async\" width=\"414\" height=\"233\" src=\"https:\/\/www.basler.com\/wp-content\/uploads\/2025\/09\/Basler-Default-Image-414x233.jpg\" class=\"img\" alt=\"\" loading=\"lazy\" title=\"\" srcset=\"https:\/\/www.basler.com\/wp-content\/uploads\/2025\/09\/Basler-Default-Image-414x233.jpg 414w, https:\/\/www.basler.com\/wp-content\/uploads\/2025\/09\/Basler-Default-Image-768x432.jpg 768w, https:\/\/www.basler.com\/wp-content\/uploads\/2025\/09\/Basler-Default-Image-1024x576.jpg 1024w, https:\/\/www.basler.com\/wp-content\/uploads\/2025\/09\/Basler-Default-Image-150x84.jpg 150w, https:\/\/www.basler.com\/wp-content\/uploads\/2025\/09\/Basler-Default-Image-1600x900.jpg 1600w, https:\/\/www.basler.com\/wp-content\/uploads\/2025\/09\/Basler-Default-Image.jpg 1920w\" sizes=\"auto, (max-width: 414px) 100vw, 414px\">        <\/picture>\n\n            <\/figure>\n\t\t<\/div>\n\n\t\t<div class=\"infos\">\n            \n            <h3 class=\"title\">BE3-81UT<\/h3>\t\t<\/div>\n\n        <a id=\"hammer_component_6a04f70d78d61\" data-component=\"link\" class=\"component component-link link cover-link style-primary\" href=\"https:\/\/www.basler.com\/de\/product\/be3-81ut\/\" title=\"BE3-81UT\" target=\"\">        <span class=\"link-text\">BE3-81UT<\/span>\n        <\/a>\n\n                \t<\/article>\n                    <\/div>\n                                    <div class=\"swiper-slide slide\">\n                        <article id=\"hammer_component_6a04f70d790dd\" data-component=\"card-product\" class=\"component component-card-product card-product primary\">\n\t\t<div class=\"image-wrapper\">\n            <figure id=\"hammer_component_6a04f70d7b8f0\" data-component=\"image\" class=\"component component-image image\">\n        <picture class=\"picture\">\n            <img decoding=\"async\" width=\"414\" height=\"233\" src=\"https:\/\/www.basler.com\/wp-content\/uploads\/2025\/09\/Basler-Default-Image-414x233.jpg\" class=\"img\" alt=\"\" loading=\"lazy\" title=\"\" srcset=\"https:\/\/www.basler.com\/wp-content\/uploads\/2025\/09\/Basler-Default-Image-414x233.jpg 414w, https:\/\/www.basler.com\/wp-content\/uploads\/2025\/09\/Basler-Default-Image-768x432.jpg 768w, https:\/\/www.basler.com\/wp-content\/uploads\/2025\/09\/Basler-Default-Image-1024x576.jpg 1024w, https:\/\/www.basler.com\/wp-content\/uploads\/2025\/09\/Basler-Default-Image-150x84.jpg 150w, https:\/\/www.basler.com\/wp-content\/uploads\/2025\/09\/Basler-Default-Image-1600x900.jpg 1600w, https:\/\/www.basler.com\/wp-content\/uploads\/2025\/09\/Basler-Default-Image.jpg 1920w\" sizes=\"auto, (max-width: 414px) 100vw, 414px\">        <\/picture>\n\n            <\/figure>\n\t\t<\/div>\n\n\t\t<div class=\"infos\">\n            \n            <h3 class=\"title\">BE3-74VL<\/h3>\t\t<\/div>\n\n        <a id=\"hammer_component_6a04f70d7c236\" data-component=\"link\" class=\"component component-link link cover-link style-primary\" href=\"https:\/\/www.basler.com\/de\/product\/be3-74vl\/\" title=\"BE3-74VL\" target=\"\">        <span class=\"link-text\">BE3-74VL<\/span>\n        <\/a>\n\n                \t<\/article>\n                    <\/div>\n                                    <div class=\"swiper-slide slide\">\n                        <article id=\"hammer_component_6a04f70d7c55b\" data-component=\"card-product\" class=\"component component-card-product card-product primary\">\n\t\t<div class=\"image-wrapper\">\n            <figure id=\"hammer_component_6a04f70d7ef80\" data-component=\"image\" class=\"component component-image image\">\n        <picture class=\"picture\">\n            <img decoding=\"async\" width=\"300\" height=\"330\" src=\"https:\/\/www.basler.com\/wp-content\/uploads\/2025\/06\/PP_Empty-Rear-Slot-Cover-Plate-for-BE1-FLEX-BPCK-A.jpg\" class=\"img\" alt=\"\" loading=\"lazy\" title=\"\" srcset=\"https:\/\/www.basler.com\/wp-content\/uploads\/2025\/06\/PP_Empty-Rear-Slot-Cover-Plate-for-BE1-FLEX-BPCK-A.jpg 300w, https:\/\/www.basler.com\/wp-content\/uploads\/2025\/06\/PP_Empty-Rear-Slot-Cover-Plate-for-BE1-FLEX-BPCK-A-136x150.jpg 136w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\">        <\/picture>\n\n            <\/figure>\n\t\t<\/div>\n\n\t\t<div class=\"infos\">\n            \t\t\t\t<strong class=\"term\">Accessories<\/strong>\n            \n            <h3 class=\"title\">Empty Rear Slot Cover Plate for BE1-FLEX (BPCK-A)<\/h3>\t\t<\/div>\n\n        <a id=\"hammer_component_6a04f70d7fcf2\" data-component=\"link\" class=\"component component-link link cover-link style-primary\" href=\"https:\/\/www.basler.com\/de\/product\/empty-be1-flex-rear-slot-cover-plate-bpck-a\/\" title=\"Empty Rear Slot Cover Plate for BE1-FLEX (BPCK-A)\" target=\"\">        <span class=\"link-text\">Empty Rear Slot Cover Plate for BE1-FLEX (BPCK-A)<\/span>\n        <\/a>\n\n                \t<\/article>\n                    <\/div>\n                                    <div class=\"swiper-slide slide\">\n                        <article id=\"hammer_component_6a04f70d7ffe6\" data-component=\"card-product\" class=\"component component-card-product card-product primary\">\n\t\t<div class=\"image-wrapper\">\n            <figure id=\"hammer_component_6a04f70d826d3\" data-component=\"image\" class=\"component component-image image\">\n        <picture class=\"picture\">\n            <img decoding=\"async\" width=\"414\" height=\"233\" src=\"https:\/\/www.basler.com\/wp-content\/uploads\/2025\/09\/Basler-Default-Image-414x233.jpg\" class=\"img\" alt=\"\" loading=\"lazy\" title=\"\" srcset=\"https:\/\/www.basler.com\/wp-content\/uploads\/2025\/09\/Basler-Default-Image-414x233.jpg 414w, https:\/\/www.basler.com\/wp-content\/uploads\/2025\/09\/Basler-Default-Image-768x432.jpg 768w, https:\/\/www.basler.com\/wp-content\/uploads\/2025\/09\/Basler-Default-Image-1024x576.jpg 1024w, https:\/\/www.basler.com\/wp-content\/uploads\/2025\/09\/Basler-Default-Image-150x84.jpg 150w, https:\/\/www.basler.com\/wp-content\/uploads\/2025\/09\/Basler-Default-Image-1600x900.jpg 1600w, https:\/\/www.basler.com\/wp-content\/uploads\/2025\/09\/Basler-Default-Image.jpg 1920w\" sizes=\"auto, (max-width: 414px) 100vw, 414px\">        <\/picture>\n\n            <\/figure>\n\t\t<\/div>\n\n\t\t<div class=\"infos\">\n            \n            <h3 class=\"title\">SR4F<\/h3>\t\t<\/div>\n\n        <a id=\"hammer_component_6a04f70d82c11\" data-component=\"link\" class=\"component component-link link cover-link style-primary\" href=\"https:\/\/www.basler.com\/de\/product\/sr4f\/\" title=\"SR4F\" target=\"\">        <span class=\"link-text\">SR4F<\/span>\n        <\/a>\n\n                \t<\/article>\n                    <\/div>\n                            <\/div>\n        <\/div>\n\n\t\t\t\t\t<div class=\"cta\">\n\t\t\t\t\t\t\t<\/div>\n\t\t    <\/div>\n    <\/section>\n\n\n\n<section  data-block-id=\"hammer_block_1305516e7ed14fbbdacb21c2f0182b87\" data-block=\"product-parts-accessories\" class=\"block block-product-parts-accessories product-parts-accessories spacing-top-default spacing-bottom-default\" id=\"parts-accessories\">\t<div class=\"wrapper\">\n        <h2 id=\"hammer_component_6a04f70da0ced\" data-component=\"headline\" class=\"component component-headline headline style-default\">Teile und Zubeh&ouml;r<\/h2>\n\n        \t\t\t<ul class=\"product-list\">\n                \t\t\t\t\t<li class=\"product-item\">\n                        <article id=\"hammer_component_6a04f70da0d7a\" data-component=\"card-product\" class=\"component component-card-product card-product primary-alt\">\n\t\t<div class=\"image-wrapper\">\n            <figure id=\"hammer_component_6a04f70da3e54\" data-component=\"image\" class=\"component component-image image\">\n        <picture class=\"picture\">\n            <img decoding=\"async\" width=\"300\" height=\"330\" src=\"https:\/\/www.basler.com\/wp-content\/uploads\/2025\/06\/PP_Standard-DIN-Rail-39.37-inches-17366-ALL.jpg\" class=\"img\" alt=\"\" loading=\"lazy\" title=\"\" srcset=\"https:\/\/www.basler.com\/wp-content\/uploads\/2025\/06\/PP_Standard-DIN-Rail-39.37-inches-17366-ALL.jpg 300w, https:\/\/www.basler.com\/wp-content\/uploads\/2025\/06\/PP_Standard-DIN-Rail-39.37-inches-17366-ALL-136x150.jpg 136w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\">        <\/picture>\n\n            <\/figure>\n\t\t<\/div>\n\n\t\t<div class=\"infos\">\n            \t\t\t\t<strong class=\"term\">Accessories<\/strong>\n            \n            <h3 class=\"title\">ES Mounting Rail, 3.0 inches (9323900001)<\/h3>\t\t<\/div>\n\n        <a id=\"hammer_component_6a04f70da4b94\" data-component=\"link\" class=\"component component-link link cover-link style-primary\" href=\"https:\/\/www.basler.com\/de\/product\/be3-mounting-rail-30-inches-9323900001\/\" title=\"ES Mounting Rail, 3.0 inches (9323900001)\" target=\"\">        <span class=\"link-text\">ES Mounting Rail, 3.0 inches (9323900001)<\/span>\n        <\/a>\n\n                \t<\/article>\n\t\t\t\t\t<\/li>\n                \t\t\t<\/ul>\n        \n        \t\t\t<div class=\"buttons\">\n                \t\t\t<\/div>\n        \t<\/div>\n    <\/section>\n\n<section  data-block-id=\"hammer_block_c51ae541d9e7b7219d9f528587e2fb91\" data-block=\"text-5\" class=\"block block-text-5 text-5 bg-dark spacing-top-default spacing-bottom-default\">    <div class=\"wrapper\">\n        <div class=\"contents\">\n            <div class=\"left\">\n                                    <h3 class=\"title\">\u2013 Leben ver\u00e4ndern mit innovativen, zuverl\u00e4ssigen Produkten, die auf Integrit\u00e4t und Nachhaltigkeit basieren.<\/h3>\n                \n            <\/div>\n\n            <div class=\"right\">\n                            <\/div>\n        <\/div>\n    <\/div>\n    <\/section>\n\n\n\n<section  data-block-id=\"hammer_block_0f18fdac3bdc0057d12ee568ccfda33f\" data-block=\"cta-banner-8\" class=\"block block-cta-banner-8 cta-banner-8 spacing-top-default spacing-bottom-large\">    <div class=\"wrapper\">\n        <div class=\"banner\">\n                            <div class=\"headline-wrapper\">\n                                        <h2 id=\"hammer_component_6a04f70ddd20e\" data-component=\"headline\" class=\"component component-headline headline style-default\">&mdash; Sprechen Sie mit uns: Ihr direkter Draht zu Support &amp; L&ouml;sungen.<\/h2>\n                <\/div>\n            \n                            <div class=\"text-wrapper\">\n                    <div id=\"hammer_component_6a04f70ddd28f\" data-component=\"rich-text\" class=\"component component-rich-text rich-text\"><p>Kontaktieren Sie Basler Electric noch heute f&uuml;r weitere Informationen zu unseren Dienstleistungen und Produkten.<\/p>\n<\/div>\n                                            <div class=\"actions\">\n                            <a id=\"hammer_component_6a04f70ddd2ca\" data-component=\"button\" class=\"component component-button button style-primary\" href=\"https:\/\/www.basler.com\/de\/kontaktieren-sie-uns\/\" target=\"\" title=\"Kontaktieren Sie uns\" aria-label=\"Kontaktieren Sie uns\">    <span class=\"button-wrapper\">\n                    <strong class=\"button-text\">Kontaktieren Sie uns<\/strong>\n        \n                    <span class=\"icon-wrapper\" aria-hidden=\"true\">\n                <span class=\"button-icon\">\n                    <?xml version=\"1.0\" encoding=\"UTF-8\"?> <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"8\" height=\"8\" viewbox=\"0 0 8 8\" fill=\"currentColor\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M7.25606 1.27007L0.526065 8L0 7.47393L6.73 0.743975H0.789112V0H8.00004V7.21087H7.25606V1.27007Z\" fill=\"currentColor\"><\/path><\/svg>                 <\/span>\n            <\/span>\n            <\/span>\n    <\/a>\n                        <\/div>\n                                    <\/div>\n            \n            <div id=\"hammer_component_6a04f70ddd3c3\" data-component=\"image-video\" class=\"component component-image-video image-video\"><figure id=\"hammer_component_6a04f70ddd3dc\" data-component=\"image\" class=\"component component-image image has-overlay\">\n        <picture class=\"picture\">\n            <img decoding=\"async\" width=\"1560\" height=\"720\" src=\"https:\/\/www.basler.com\/wp-content\/uploads\/2024\/11\/Banner-1.jpg\" class=\"img\" alt=\"\" loading=\"lazy\" title=\"\" srcset=\"https:\/\/www.basler.com\/wp-content\/uploads\/2024\/11\/Banner-1.jpg 1560w, https:\/\/www.basler.com\/wp-content\/uploads\/2024\/11\/Banner-1-768x354.jpg 768w, https:\/\/www.basler.com\/wp-content\/uploads\/2024\/11\/Banner-1-1024x473.jpg 1024w, https:\/\/www.basler.com\/wp-content\/uploads\/2024\/11\/Banner-1-150x69.jpg 150w, https:\/\/www.basler.com\/wp-content\/uploads\/2024\/11\/Banner-1-414x191.jpg 414w\" sizes=\"auto, (max-width: 1560px) 100vw, 1560px\">        <\/picture>\n\n            <\/figure>\n<\/div>\n        <\/div>\n    <\/div>\n    <\/section>","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":60438,"parent":0,"menu_order":5,"template":"","product-category":[638,646],"class_list":["post-3189","product","type-product","status-publish","has-post-thumbnail","hentry","product-category-protective-relay-systems","product-category-industrial-relays"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ES Series Protection Relays | Basler Electric<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.basler.com\/de\/product\/es-series-protection-relays\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ES Series Protection Relays | Basler Electric\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.basler.com\/de\/product\/es-series-protection-relays\/\" \/>\n<meta property=\"og:site_name\" content=\"Basler Electric\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-02T15:50:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.bestsoftwaredepot.com\/wp-content\/uploads\/2025\/07\/ES-27_ES-59_ES-2759-Edit-Small_web-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"330\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.basler.com\\\/de\\\/product\\\/es-series-protection-relays\\\/\",\"url\":\"https:\\\/\\\/www.basler.com\\\/de\\\/product\\\/es-series-protection-relays\\\/\",\"name\":\"ES Series Protection Relays | Basler Electric\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/catalog.basler.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.basler.com\\\/de\\\/product\\\/es-series-protection-relays\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.basler.com\\\/de\\\/product\\\/es-series-protection-relays\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.basler.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/ES-27_ES-59_ES-2759-Edit-Small_web-1.jpg\",\"datePublished\":\"2025-07-14T02:11:11+00:00\",\"dateModified\":\"2026-03-02T15:50:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.basler.com\\\/de\\\/product\\\/es-series-protection-relays\\\/#breadcrumb\"},\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.basler.com\\\/de\\\/product\\\/es-series-protection-relays\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\\\/\\\/www.basler.com\\\/de\\\/product\\\/es-series-protection-relays\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.basler.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/ES-27_ES-59_ES-2759-Edit-Small_web-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.basler.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/ES-27_ES-59_ES-2759-Edit-Small_web-1.jpg\",\"width\":300,\"height\":330},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.basler.com\\\/de\\\/product\\\/es-series-protection-relays\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/e2powersystems.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Products\",\"item\":\"https:\\\/\\\/www.basler.com\\\/de\\\/product\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"ES Series Protection Relays\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/catalog.basler.com\\\/#website\",\"url\":\"https:\\\/\\\/catalog.basler.com\\\/\",\"name\":\"Basler Electric\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/catalog.basler.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/catalog.basler.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-DE\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/catalog.basler.com\\\/#organization\",\"name\":\"Basler Electric\",\"url\":\"https:\\\/\\\/catalog.basler.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\\\/\\\/catalog.basler.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.basler.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Basler-Logo-Favicon.png\",\"contentUrl\":\"https:\\\/\\\/www.basler.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Basler-Logo-Favicon.png\",\"width\":512,\"height\":512,\"caption\":\"Basler Electric\"},\"image\":{\"@id\":\"https:\\\/\\\/catalog.basler.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ES Series Protection Relays | Basler Electric","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.basler.com\/de\/product\/es-series-protection-relays\/","og_locale":"de_DE","og_type":"article","og_title":"ES Series Protection Relays | Basler Electric","og_url":"https:\/\/www.basler.com\/de\/product\/es-series-protection-relays\/","og_site_name":"Basler Electric","article_modified_time":"2026-03-02T15:50:28+00:00","og_image":[{"width":300,"height":330,"url":"https:\/\/www.bestsoftwaredepot.com\/wp-content\/uploads\/2025\/07\/ES-27_ES-59_ES-2759-Edit-Small_web-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.basler.com\/de\/product\/es-series-protection-relays\/","url":"https:\/\/www.basler.com\/de\/product\/es-series-protection-relays\/","name":"ES Series Protection Relays | Basler Electric","isPartOf":{"@id":"https:\/\/catalog.basler.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.basler.com\/de\/product\/es-series-protection-relays\/#primaryimage"},"image":{"@id":"https:\/\/www.basler.com\/de\/product\/es-series-protection-relays\/#primaryimage"},"thumbnailUrl":"https:\/\/www.basler.com\/wp-content\/uploads\/2025\/07\/ES-27_ES-59_ES-2759-Edit-Small_web-1.jpg","datePublished":"2025-07-14T02:11:11+00:00","dateModified":"2026-03-02T15:50:28+00:00","breadcrumb":{"@id":"https:\/\/www.basler.com\/de\/product\/es-series-protection-relays\/#breadcrumb"},"inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.basler.com\/de\/product\/es-series-protection-relays\/"]}]},{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/www.basler.com\/de\/product\/es-series-protection-relays\/#primaryimage","url":"https:\/\/www.basler.com\/wp-content\/uploads\/2025\/07\/ES-27_ES-59_ES-2759-Edit-Small_web-1.jpg","contentUrl":"https:\/\/www.basler.com\/wp-content\/uploads\/2025\/07\/ES-27_ES-59_ES-2759-Edit-Small_web-1.jpg","width":300,"height":330},{"@type":"BreadcrumbList","@id":"https:\/\/www.basler.com\/de\/product\/es-series-protection-relays\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/e2powersystems.com\/de\/"},{"@type":"ListItem","position":2,"name":"Products","item":"https:\/\/www.basler.com\/de\/product\/"},{"@type":"ListItem","position":3,"name":"ES Series Protection Relays"}]},{"@type":"WebSite","@id":"https:\/\/catalog.basler.com\/#website","url":"https:\/\/catalog.basler.com\/","name":"Basler Electric","description":"","publisher":{"@id":"https:\/\/catalog.basler.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/catalog.basler.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-DE"},{"@type":"Organization","@id":"https:\/\/catalog.basler.com\/#organization","name":"Basler Electric","url":"https:\/\/catalog.basler.com\/","logo":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/catalog.basler.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.basler.com\/wp-content\/uploads\/2025\/10\/Basler-Logo-Favicon.png","contentUrl":"https:\/\/www.basler.com\/wp-content\/uploads\/2025\/10\/Basler-Logo-Favicon.png","width":512,"height":512,"caption":"Basler Electric"},"image":{"@id":"https:\/\/catalog.basler.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.basler.com\/de\/wp-json\/wp\/v2\/product\/3189","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.basler.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.basler.com\/de\/wp-json\/wp\/v2\/types\/product"}],"author":[{"embeddable":true,"href":"https:\/\/www.basler.com\/de\/wp-json\/wp\/v2\/users\/1"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.basler.com\/de\/wp-json\/wp\/v2\/media\/60438"}],"wp:attachment":[{"href":"https:\/\/www.basler.com\/de\/wp-json\/wp\/v2\/media?parent=3189"}],"wp:term":[{"taxonomy":"product-category","embeddable":true,"href":"https:\/\/www.basler.com\/de\/wp-json\/wp\/v2\/product-category?post=3189"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}