{"id":37013,"date":"2025-07-01T12:54:24","date_gmt":"2025-07-01T17:54:24","guid":{"rendered":"https:\/\/www.basler.com\/product\/es-55-power-factor-relay\/"},"modified":"2026-02-27T14:44:21","modified_gmt":"2026-02-27T20:44:21","slug":"es-55-power-factor-relay","status":"publish","type":"product","link":"https:\/\/www.basler.com\/es\/product\/es-series-protection-relays\/es-55-power-factor-relay\/","title":{"rendered":"ES-55, Power Factor Relay"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":60135,"parent":3189,"menu_order":1,"template":"","product-category":[],"class_list":["post-37013","product","type-product","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ES-55, Power Factor Relay | Basler Electric<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.basler.com\/es\/product\/es-series-protection-relays\/es-55-power-factor-relay\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ES-55, Power Factor Relay | Basler Electric\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.basler.com\/es\/product\/es-series-protection-relays\/es-55-power-factor-relay\/\" \/>\n<meta property=\"og:site_name\" content=\"Basler Electric\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-27T20:44:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.baslerservices.com\/wp-content\/uploads\/2025\/07\/PP_ES-55.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"330\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.basler.com\\\/es\\\/product\\\/es-series-protection-relays\\\/es-55-power-factor-relay\\\/\",\"url\":\"https:\\\/\\\/www.basler.com\\\/es\\\/product\\\/es-series-protection-relays\\\/es-55-power-factor-relay\\\/\",\"name\":\"ES-55, Power Factor Relay | Basler Electric\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/catalog.basler.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.basler.com\\\/es\\\/product\\\/es-series-protection-relays\\\/es-55-power-factor-relay\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.basler.com\\\/es\\\/product\\\/es-series-protection-relays\\\/es-55-power-factor-relay\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.basler.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/PP_ES-55.jpg\",\"datePublished\":\"2025-07-01T17:54:24+00:00\",\"dateModified\":\"2026-02-27T20:44:21+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.basler.com\\\/es\\\/product\\\/es-series-protection-relays\\\/es-55-power-factor-relay\\\/#breadcrumb\"},\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.basler.com\\\/es\\\/product\\\/es-series-protection-relays\\\/es-55-power-factor-relay\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\\\/\\\/www.basler.com\\\/es\\\/product\\\/es-series-protection-relays\\\/es-55-power-factor-relay\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.basler.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/PP_ES-55.jpg\",\"contentUrl\":\"https:\\\/\\\/www.basler.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/PP_ES-55.jpg\",\"width\":300,\"height\":330},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.basler.com\\\/es\\\/product\\\/es-series-protection-relays\\\/es-55-power-factor-relay\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/sourceautosoftware.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Products\",\"item\":\"https:\\\/\\\/www.basler.com\\\/es\\\/product\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"ES Series Protection Relays\",\"item\":\"https:\\\/\\\/www.bestsoftwaredepot.com\\\/pt-br\\\/product\\\/es-series-protection-relays\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"ES-55, Power Factor Relay\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/catalog.basler.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/catalog.basler.com\\\/es\\\/\",\"name\":\"Basler Electric\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/catalog.basler.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/catalog.basler.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-ES\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/catalog.basler.com\\\/es\\\/#organization\",\"name\":\"Basler Electric\",\"url\":\"https:\\\/\\\/catalog.basler.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\\\/\\\/catalog.basler.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.basler.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Basler-Logo-Favicon.png\",\"contentUrl\":\"https:\\\/\\\/www.basler.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Basler-Logo-Favicon.png\",\"width\":512,\"height\":512,\"caption\":\"Basler Electric\"},\"image\":{\"@id\":\"https:\\\/\\\/catalog.basler.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ES-55, Power Factor Relay | Basler Electric","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.basler.com\/es\/product\/es-series-protection-relays\/es-55-power-factor-relay\/","og_locale":"es_ES","og_type":"article","og_title":"ES-55, Power Factor Relay | Basler Electric","og_url":"https:\/\/www.basler.com\/es\/product\/es-series-protection-relays\/es-55-power-factor-relay\/","og_site_name":"Basler Electric","article_modified_time":"2026-02-27T20:44:21+00:00","og_image":[{"width":300,"height":330,"url":"https:\/\/www.baslerservices.com\/wp-content\/uploads\/2025\/07\/PP_ES-55.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.basler.com\/es\/product\/es-series-protection-relays\/es-55-power-factor-relay\/","url":"https:\/\/www.basler.com\/es\/product\/es-series-protection-relays\/es-55-power-factor-relay\/","name":"ES-55, Power Factor Relay | Basler Electric","isPartOf":{"@id":"https:\/\/catalog.basler.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.basler.com\/es\/product\/es-series-protection-relays\/es-55-power-factor-relay\/#primaryimage"},"image":{"@id":"https:\/\/www.basler.com\/es\/product\/es-series-protection-relays\/es-55-power-factor-relay\/#primaryimage"},"thumbnailUrl":"https:\/\/www.basler.com\/wp-content\/uploads\/2025\/07\/PP_ES-55.jpg","datePublished":"2025-07-01T17:54:24+00:00","dateModified":"2026-02-27T20:44:21+00:00","breadcrumb":{"@id":"https:\/\/www.basler.com\/es\/product\/es-series-protection-relays\/es-55-power-factor-relay\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.basler.com\/es\/product\/es-series-protection-relays\/es-55-power-factor-relay\/"]}]},{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/www.basler.com\/es\/product\/es-series-protection-relays\/es-55-power-factor-relay\/#primaryimage","url":"https:\/\/www.basler.com\/wp-content\/uploads\/2025\/07\/PP_ES-55.jpg","contentUrl":"https:\/\/www.basler.com\/wp-content\/uploads\/2025\/07\/PP_ES-55.jpg","width":300,"height":330},{"@type":"BreadcrumbList","@id":"https:\/\/www.basler.com\/es\/product\/es-series-protection-relays\/es-55-power-factor-relay\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/sourceautosoftware.com\/es\/"},{"@type":"ListItem","position":2,"name":"Products","item":"https:\/\/www.basler.com\/es\/product\/"},{"@type":"ListItem","position":3,"name":"ES Series Protection Relays","item":"https:\/\/www.bestsoftwaredepot.com\/pt-br\/product\/es-series-protection-relays\/"},{"@type":"ListItem","position":4,"name":"ES-55, Power Factor Relay"}]},{"@type":"WebSite","@id":"https:\/\/catalog.basler.com\/es\/#website","url":"https:\/\/catalog.basler.com\/es\/","name":"Basler Electric","description":"","publisher":{"@id":"https:\/\/catalog.basler.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/catalog.basler.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"},{"@type":"Organization","@id":"https:\/\/catalog.basler.com\/es\/#organization","name":"Basler Electric","url":"https:\/\/catalog.basler.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/catalog.basler.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.basler.com\/wp-content\/uploads\/2025\/10\/Basler-Logo-Favicon.png","contentUrl":"https:\/\/www.basler.com\/wp-content\/uploads\/2025\/10\/Basler-Logo-Favicon.png","width":512,"height":512,"caption":"Basler Electric"},"image":{"@id":"https:\/\/catalog.basler.com\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.basler.com\/es\/wp-json\/wp\/v2\/product\/37013","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.basler.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.basler.com\/es\/wp-json\/wp\/v2\/types\/product"}],"author":[{"embeddable":true,"href":"https:\/\/www.basler.com\/es\/wp-json\/wp\/v2\/users\/1"}],"up":[{"embeddable":true,"href":"https:\/\/www.basler.com\/es\/wp-json\/wp\/v2\/product\/3189"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.basler.com\/es\/wp-json\/wp\/v2\/media\/60135"}],"wp:attachment":[{"href":"https:\/\/www.basler.com\/es\/wp-json\/wp\/v2\/media?parent=37013"}],"wp:term":[{"taxonomy":"product-category","embeddable":true,"href":"https:\/\/www.basler.com\/es\/wp-json\/wp\/v2\/product-category?post=37013"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}